{"id":6773,"date":"2013-06-19T13:23:35","date_gmt":"2013-06-19T13:23:35","guid":{"rendered":"http:\/\/sorridentsfranchising.wordpress.com\/?p=6773"},"modified":"2013-06-19T13:23:35","modified_gmt":"2013-06-19T13:23:35","slug":"veja-a-historia-da-dentista-que-esta-por-tras-da-maior-rede-odontologica-do-brasil","status":"publish","type":"post","link":"https:\/\/sorridents.com.br\/business\/veja-a-historia-da-dentista-que-esta-por-tras-da-maior-rede-odontologica-do-brasil\/","title":{"rendered":"Veja a hist\u00f3ria da dentista que est\u00e1 por tr\u00e1s da maior rede odontol\u00f3gica do Brasil"},"content":{"rendered":"<p>A dentista e empres\u00e1ria Carla Sarni construiu do zero a maior rede de cl\u00ednicas odontol\u00f3gica do Pa\u00eds<br \/>\nKarla Santana Mamona<\/p>\n<p>S\u00c3O PAULO &#8211;\u00a0N\u00e3o faltam motivos para a empres\u00e1ria por tr\u00e1s da marca Sorridents sorrir \u00e0 toa. H\u00e1 17 anos, a dra. Carla Renata Sarni comanda a maior rede de cl\u00ednicas odontol\u00f3gicas do Brasil e a segunda maior empresa de odontologia em todo o mundo. Atualmente, s\u00e3o mais de 180 cl\u00ednicas de tratamento dent\u00e1rio em 16 estados brasileiros e mais de 1 milh\u00e3o de pessoas atendidas.<\/p>\n<p>Carla nem sempre sonhou em ser dentista. Ainda na adolesc\u00eancia, estudava para ser professora de ensino infantil. Em Pitangueiras, cidade do interior paulista, ela quase se formou no Magist\u00e9rio &#8211; faltaram apenas seis meses para que ela se tornasse professora. Um convite do primo que iria prestar vestibular em odontologia na cidade de Alfenas, em Minas Gerais, fez com que ela mudasse de profiss\u00e3o.<\/p>\n<p>Sem muita esperan\u00e7a de passar no vestibular pois sempre havia estudado em escola p\u00fablica, ela resolveu arriscar. E passou! Mas como a fam\u00edlia n\u00e3o tinha condi\u00e7\u00f5es de manter uma filha estudando em outra cidade &#8211; seu pai trabalhava como motorista e a m\u00e3e como cabeleireira &#8211; Carla fez um acordo com a m\u00e3e. Disse que tentaria se manter na cidade mineira por seis meses e, se n\u00e3o conseguisse, voltaria para Pitangueiras e terminaria o Magist\u00e9rio. Neste per\u00edodo, a m\u00e3e comprou uma lojinha de roupa e virou fornecedora de Carla. A jovem estudante vendia roupas, sapatos e at\u00e9 bombom de leite ninho para tentar se manter na universidade. \u201cMeu apelido na escola era camel\u00f4\u201d, conta.<\/p>\n<figure id=\"imgNewsContainer\"><\/figure>\n<p>Carla nem sempre sonhou em ser dentista. Ainda na adolesc\u00eancia, estudava para ser professora (Rodrigo Paiva)<\/p>\n<p>Durante o dia, Carla levava na mochila apenas algumas encomendas para alunos e professores. As vendas mesmo aconteciam \u00e0 noite. Ap\u00f3s um dia inteiro de aula, ela passava nas rep\u00fablicas dos colegas para oferecer seus produtos. \u201cPassava de rep\u00fablica em rep\u00fablica todo dia, at\u00e9 a meia noite.\u201d Tanta dedica\u00e7\u00e3o e empenho deram certo. Com as vendas, al\u00e9m de conseguir pagar seus pr\u00f3prios custos, ela mandava dinheiro para m\u00e3e, que acabou ficando vi\u00fava enquanto ela estudava.<\/p>\n<p>A hoje doutora tamb\u00e9m encontrava tempo para participar de um projeto social desenvolvido pela faculdade, prestando atendimento aos moradores da regi\u00e3o, que n\u00e3o tinham nem dinheiro nem h\u00e1bito de ir ao dentista. Todos os estudantes eram obrigados a frequentar o projeto durante tr\u00eas meses pois as horas eram contadas no tempo necess\u00e1rio de est\u00e1gio obrigat\u00f3rio para se formar. Mas Carla gostou tanto que participou do projeto o ano inteiro.<\/p>\n<p>\u201cAquilo me fazia bem, eu gostava de ajudar quem tinha menos do que eu. E mais tarde eu colhi os frutos.\u201d Ela se refere ao fato de ter se tornado uma das profissionais mais r\u00e1pidas e experientes do hospital em que fazia resid\u00eancia. \u201cEu me destacava, j\u00e1 tinha a pr\u00e1tica de ter feito muitas cirurgias de gra\u00e7a.\u201d Ao final da resid\u00eancia, fez as malas novamente, com destino \u00e0 casa dos tios em S\u00e3o Paulo. \u201cEu cheguei com a ideia de dar uma odontologia digna para a classe C e D.\u201d<\/p>\n<p>Dentes novos na cidade grande<br \/>\nNa capital paulista, passou por alguns consult\u00f3rios at\u00e9 encontrar um que lhe agradasse. A dentista lembra que trabalhou em lugares que n\u00e3o eram t\u00e3o limpos como ela imaginava e com donos n\u00e3o muito honestos. Mas em um consult\u00f3rio na Vila C\u00edsper, na zona leste da cidade, seu atendimento come\u00e7ou a fazer sucesso. Os pacientes ficavam at\u00e9 seis meses na fila de espera para serem atendidos por ela.<\/p>\n<p>Em um s\u00e1bado \u00e0 noite, ap\u00f3s um dia inteiro de trabalho, um homem abordou a dentista &#8211; que estava fechando o consult\u00f3rio &#8211; para pedir que lhe ajudasse, pois estava com dor de dente. Como ele estava desempregado, o tratamento seria gratuito. Carla topou. Ela nem imaginava que esse homem, ap\u00f3s alguns meses, se tornaria pastor. Em seus cultos, ele contava sobre a boa a\u00e7\u00e3o da dentista, a \u00fanica que se prop\u00f4s em ajud\u00e1-lo quando ele n\u00e3o tinha dinheiro. \u201cToda vez que ele contava isso na igreja, no dia seguinte tinha fila de espera no consult\u00f3rio de pacientes para eu atender.\u201d<\/p>\n<p>Com um bom n\u00famero de pacientes, Carla comunicou que sairia daquele emprego para montar um consult\u00f3rio pr\u00f3prio. O dono desse consult\u00f3rio lhe fez uma proposta, para que ela comprasse o estabelecimento. Ela aceitou, come\u00e7ou a faturar alto e pagou pela carteira de clientes em 12 meses.<\/p>\n<p>Neste per\u00edodo, sua av\u00f3 e uma tia tinham acabado de pagar o carn\u00ea de uma cadeira nova de dentista. Em vez de trocar a cadeira velha pela nova, ela decidiu alugar mais uma sala e chamar uma amiga para trabalhar com ela. Assim nasceu a Sorridents.<\/p>\n<p>J\u00e1 em sua empresa, Carla convidou outros profissionais com especialidades diferentes para trabalhar com ela. Em tr\u00eas anos, as cinco salas dispon\u00edveis ficaram pequenas. \u201cN\u00e3o tinha mais para onde crescer.\u201d<\/p>\n<p>Por coincid\u00eancias do destino, uma vizinha colocou seu im\u00f3vel \u00e0 venda. O problema \u00e9 que Carla n\u00e3o tinha dinheiro para comprar, j\u00e1 que tinha investido tudo que ganhou nas salas alugadas. Nesta \u00e9poca, ela tinha acabado de comprar um carro por meio de um cons\u00f3rcio. A solu\u00e7\u00e3o encontrada foi vender o carro para dar de entrada no im\u00f3vel e financiar o restante no banco. \u201cEu fiquei uma semana andando de carro, estava me achando. Mas tive que voltar a andar de \u00f4nibus rapidinho\u201d, recorda.<\/p>\n<p>Com o investimento na empresa, at\u00e9 o marido de Carla, Cl\u00e9ber Soares, trocou de profiss\u00e3o. O militar que cursava faculdade de An\u00e1lise de Sistemas decidiu estudar Odontologia. Com a ajuda do marido, a Sorridents n\u00e3o parava de crescer. Juntos, eles decidiram montar um escrit\u00f3rio para expandir o n\u00famero de consult\u00f3rios. Em 2005, a Sorridents tinha 23 unidades em v\u00e1rios bairros em S\u00e3o Paulo. Hoje s\u00e3o mais de 180 unidades em todo o Brasil.<\/p>\n<p>Da odontologia ao franchising<br \/>\nCom a expans\u00e3o dos neg\u00f3cios, muitos dentistas que eram parceiros da empresa de Carla pediam para ter um consult\u00f3rio igual ao da Sorridents. Al\u00e9m disso, alguns empres\u00e1rios procuraram o casal em busca de unidades para que os filhos rec\u00e9m-formados pudessem trabalhar. Com tamanha procura, Carla decidiu formatar a empresa no segmento de franquia. A estrat\u00e9gia deu certo. Em 2012, o faturamento da rede foi de R$ 182 milh\u00f5es. A expectativa \u00e9 de que, at\u00e9 2016, a Sorridents tenha 500 unidades em todo o Pa\u00eds.<\/p>\n<p>Carla explica que o sucesso da empresa \u00e9 baseado em tr\u00eas pilares: pre\u00e7o justo, qualidade e conveni\u00eancia. Para ela, o sucesso \u00e9 conseq\u00fc\u00eancia de um trabalho \u00e1rduo e bem feito. \u201cQuando voc\u00ea levanta todo dia de manh\u00e3 exclusivamente pelo dinheiro, voc\u00ea n\u00e3o tem todo o sucesso que poderia ter\u201d, finaliza.<\/p>\n<p>Fonte: InfoMoney<\/p>\n","protected":false},"excerpt":{"rendered":"A dentista e empres\u00e1ria Carla Sarni construiu do zero a maior rede de cl\u00ednicas odontol\u00f3gica do Pa\u00eds Karla Santana Mamona S\u00c3O PAULO &#8211;\u00a0N\u00e3o faltam motivos para a empres\u00e1ria por tr\u00e1s da marca Sorridents sorrir \u00e0 toa. H\u00e1 17 anos, a dra. Carla Renata Sarni comanda a maior rede de cl\u00ednicas odontol\u00f3gicas do Brasil e a&#8230; <a class=\"view-article\" href=\"https:\/\/sorridents.com.br\/business\/veja-a-historia-da-dentista-que-esta-por-tras-da-maior-rede-odontologica-do-brasil\/\">Ver artigo<\/a>","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/posts\/6773"}],"collection":[{"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/comments?post=6773"}],"version-history":[{"count":0,"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/posts\/6773\/revisions"}],"wp:attachment":[{"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/media?parent=6773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/categories?post=6773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sorridents.com.br\/business\/wp-json\/wp\/v2\/tags?post=6773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}